{"id":2031,"date":"2019-12-04T23:46:41","date_gmt":"2019-12-04T22:46:41","guid":{"rendered":"https:\/\/moissyfitness.com\/?page_id=2031"},"modified":"2023-07-21T00:12:43","modified_gmt":"2023-07-20T22:12:43","slug":"reglement-interieur","status":"publish","type":"page","link":"https:\/\/moissyfitness.com\/index.php\/nous\/reglement-interieur\/","title":{"rendered":"R\u00e8glement Int\u00e9rieur"},"content":{"rendered":"<p>[vc_row][vc_column][vc_empty_space]<div id=\"ultimate-heading-31816a97947297be8\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-31816a97947297be8 uvc-7767  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-31816a97947297be8 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;\">Notre R\u00e8glement Int\u00e9rieur<\/h2><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-31816a97947297be8 .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><\/p>\n<p style=\"text-align: center;\"><strong>Le pr\u00e9sent r\u00e8glement int\u00e9rieur a pour but de compl\u00e9ter les statuts et de fixer dans les d\u00e9tails les r\u00e8gles qui r\u00e9gissent le bon fonctionnement de l\u2019association Moissy Fitness. Les statuts complets peuvent \u00eatre consult\u00e9s par tout adh\u00e9rent qui le souhaite.<\/strong><\/p>\n<p><\/div><\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space]<div class=\"uavc-list-icon uavc-list-icon-wrapper ult-adjust-bottom-margin   \"><ul class=\"uavc-list\"><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8815\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"icomoon-the7-font-the7-login-03\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8815 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art. 1<\/strong> \u2013 <strong>Inscription<\/strong>\u00a0: Seules les personnes dont le dossier d\u2019inscription est <strong><u>COMPLET<\/u> <\/strong>seront consid\u00e9r\u00e9es comme membres et admises \u00e0 participer aux cours.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-7725\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"far fa-hand-peace\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-7725 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 2<\/strong> &#8211; <strong>Cours d\u2019essai<\/strong>\u00a0: 1 seul cours d\u2019essai sera accept\u00e9 par personne. Au del\u00e0 de ce cours, tous cours effectu\u00e9s sans dossier d\u2019inscription COMPLET seront dus \u00e0 l\u2019association pour un montant de 5\u20ac.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8942\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"icomoon-the7-font-the7-map-02\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8942 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 3<\/strong> \u2013 <strong>D\u00e9roulement<\/strong>\u00a0: Les cours ont lieu \u00e0 la salle de Lugny, <em>178 rue des marronniers \u00e0 Moissy Cramayel<\/em>.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-6927\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-euro-sign\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-6927 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 4<\/strong> \u2013 <strong>Remboursements<\/strong>\u00a0: Les demandes de remboursement seront accept\u00e9es jusqu\u2019au 30 septembre inclus. Au del\u00e0, les inscriptions seront d\u00e9finitives, <strong><u>sans aucune possibilit\u00e9 de remboursement<\/u><\/strong>. <strong><u>Toute ann\u00e9e commenc\u00e9e est due dans sa totalit\u00e9<\/u><\/strong>.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8483\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-exclamation-triangle\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8483 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 5<\/strong> &#8211; <strong>Locaux\u00a0:<\/strong> Il est fortement d\u00e9conseill\u00e9 d\u2019apporter, dans la salle et les vestiaires, des objets de valeur. En cas de vol ou d\u00e9gradation la seule responsabilit\u00e9 de l\u2019adh\u00e9rent est engag\u00e9e. MOISSY FITNESS ne pourra \u00eatre tenu pour responsable.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-4840\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-check\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-4840 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 6<\/strong> \u2013 <strong>Chaussures\u00a0et hygi\u00e8ne :<\/strong> Il est <strong>OBLIGATOIRE<\/strong> d\u2019apporter une paire de chaussures propres et r\u00e9serv\u00e9es \u00e0 la pratique du fitness en int\u00e9rieur. Si un adh\u00e9rent ne se pr\u00e9sente pas avec cette derni\u00e8re, l\u2019acc\u00e8s \u00e0 la salle lui sera refus\u00e9. Par mesure d\u2019hygi\u00e8ne, il est demand\u00e9 d\u2019amener une <strong>grande serviette \u00e9ponge<\/strong> pour les exercices sur tapis.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-6213\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#000000;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-bullhorn\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-6213 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 7<\/strong> \u2013 <strong>Mat\u00e9riel<\/strong>\u00a0: A l\u2019issue de chaque cours, le mat\u00e9riel mis \u00e0 disposition (steps, tapis, b\u00e2tons, lestes, etc. \u2026) devra \u00eatre correctement rang\u00e9 dans les placards pr\u00e9vus \u00e0 cet effet. Les bouteilles d\u2019eau vides seront jet\u00e9es. La salle de Lugny n\u2019\u00e9tant pas r\u00e9serv\u00e9e au seul usage de MOISSY FITNESS, chacun doit veiller au respect des lieux.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-9247\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:16px;display:inline-block;\">\n\t<i class=\"icomoon-the7-font-telegram\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-9247 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 8<\/strong>\u00a0\u2013 <strong>Mineurs<\/strong> : <span style=\"font-weight: 400;\">Les cours sont ouverts aux adh\u00e9rents \u00e0 partir de 16 ans r\u00e9volus au moment de l\u2019inscription. Il est obligatoire de pr\u00e9senter une autorisation parentale sign\u00e9e par au moins un repr\u00e9sentant l\u00e9gal du mineur.<\/span><\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-2315\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-grin-beam\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-2315 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 9<\/strong>\u00a0&#8211; \u00a0<strong>Comportement<\/strong>\u00a0: Tout membre est tenu d\u2019observer une attitude correcte dans ses gestes et propos, tant envers les dirigeants et professeurs qu\u2019envers les autres adh\u00e9rents, d\u2019ex\u00e9cuter les s\u00e9ances telles qu\u2019elles sont formul\u00e9es et de respecter les consignes de s\u00e9curit\u00e9 donn\u00e9es. Toute infraction fera l\u2019objet d\u2019un avertissement d\u2019abord oral, puis \u00e9crit.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-4635\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-video\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-4635 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 10<\/strong>\u00a0&#8211; <strong>Droit \u00e0 l\u2019image<\/strong> : <span style=\"font-weight: 400;\">J\u2019autorise express\u00e9ment les membres de Moissy Fitness \u00e0 utiliser les images fixes ou audiovisuelles sur lesquelles mes enfants et\/ou ma personne pourraient appara\u00eetre, prises \u00e0 l\u2019occasion des participations aux cours et autres \u00e9v\u00e9nements tels que les conventions sur tous les supports y compris les documents promotionnels et\/ou publicitaires dans le monde entier, pour une dur\u00e9e de 10 ans \u00e0 partir de la prise de vue, reconductibles tacitement \u00e0 \u00e9ch\u00e9ance sauf demande de refus.<\/span><\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-4997\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-bacterium\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-4997 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 11<\/strong>\u00a0&#8211; <strong>En cas de crise sanitaire<\/strong>\u00a0: L&rsquo;association mettra \u00e0 disposition tout le mat\u00e9riel n\u00e9cessaire et les gestes barri\u00e8res pour assurer la bonne r\u00e9alisation des activit\u00e9s. En cas d&rsquo;impossibilit\u00e9 d&rsquo;assurer la s\u00e9curit\u00e9 des adh\u00e9rents, des professeurs et des b\u00e9n\u00e9voles selon les directives gouvernementales, l&rsquo;association pourrait proposer des cours en distanciel.<\/span><\/div><\/li><li><div class=\"uavc-list-content\" id=\"list-icon-wrap-8550\">\n<div class=\"uavc-list-icon  \" data-animation=\"\" data-animation-delay=\"03\" style=\"margin-right:15px;\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon none \"  style=\"color:#333333;font-size:16px;display:inline-block;\">\n\t<i class=\"fas fa-trophy\"><\/i>\n<\/div><\/div><\/div>\n<\/div><span  data-ultimate-target='#list-icon-wrap-8550 .uavc-list-desc'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"uavc-list-desc ult-responsive\" style=\"\"><strong>Art 12<\/strong>\u00a0&#8211; <strong>Assembl\u00e9e g\u00e9n\u00e9rale<\/strong>\u00a0: Elle a lieu en fin de saison sportive afin de pr\u00e9senter le bilan de la saison ainsi que les projets et perspectives de l&rsquo;ann\u00e9e suivante. Les d\u00e9lib\u00e9rations sont adopt\u00e9es \u00e0 la majorit\u00e9 des voix des membres pr\u00e9sents ou repr\u00e9sent\u00e9s.<\/span><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space]<div id=\"ultimate-heading-24516a97947298297\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-24516a97947298297 uvc-541  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-24516a97947298297 h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"--font-weight:theme;\">Cher.e Adh\u00e9rent.e<\/h2><\/div><div class=\"uvc-sub-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-24516a97947298297 .uvc-sub-heading '  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><strong>Le Bureau et les professeurs se r\u00e9servent le droit d\u2019exclure temporairement ou d\u00e9finitivement du club sans aucun remboursement, toute personne qui ne se conformerait pas au pr\u00e9sent r\u00e8glement ou ferait preuve d\u2019une attitude incompatible avec toute vie associative.<\/strong><\/div><\/div>[vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":25,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2031","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/pages\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/comments?post=2031"}],"version-history":[{"count":22,"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/pages\/2031\/revisions"}],"predecessor-version":[{"id":2928,"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/pages\/2031\/revisions\/2928"}],"up":[{"embeddable":true,"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/pages\/25"}],"wp:attachment":[{"href":"https:\/\/moissyfitness.com\/index.php\/wp-json\/wp\/v2\/media?parent=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}